{"id":464,"date":"2021-02-08T21:59:05","date_gmt":"2021-02-08T20:59:05","guid":{"rendered":"https:\/\/nuovazavalonolbia.com\/website\/?p=464"},"modified":"2021-02-08T21:59:05","modified_gmt":"2021-02-08T20:59:05","slug":"croce-del-sud","status":"publish","type":"post","link":"https:\/\/nuovazavalonolbia.com\/website\/croce-del-sud\/","title":{"rendered":"CROCE DEL SUD"},"content":{"rendered":"[vc_row css=&#8221;.vc_custom_1612382354859{padding-top: 20px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;]<div class=\"wpex-slider-preloaderimg\"><img loading=\"lazy\" decoding=\"async\" data-no-lazy=\"1\" class=\"skip-lazy\" src=\"https:\/\/i0.wp.com\/nuovazavalonolbia.com\/website\/wp-content\/uploads\/2021\/02\/CROCE-DEL-SUD.jpg?fit=578%2C810&#038;ssl=1\" alt=\"\" width=\"578\" height=\"810\" \/><\/div><div class=\"vcex-module wpex-slider slider-pro vcex-image-slider wpex-clr wpex-lightbox-group\" data-auto-play-delay=\"5000\" data-thumbnails=\"true\" data-animation-speed=\"600\" data-height-animation-duration=\"500\" data-thumbnail-height=\"70\" data-thumbnail-width=\"70\" data-show_title=\"false\"><div class=\"wpex-slider-slides sp-slides\"><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media\"><a href=\"https:\/\/i0.wp.com\/nuovazavalonolbia.com\/website\/wp-content\/uploads\/2021\/02\/CROCE-DEL-SUD.jpg?fit=578%2C810&#038;ssl=1\" class=\"vcex-flexslider-entry-img wpex-slider-media-link wpex-lightbox-group-item\"><img loading=\"lazy\" decoding=\"async\" data-no-lazy=\"1\" class=\"skip-lazy\" src=\"https:\/\/i0.wp.com\/nuovazavalonolbia.com\/website\/wp-content\/uploads\/2021\/02\/CROCE-DEL-SUD.jpg?fit=578%2C810&#038;ssl=1\" alt=\"\" width=\"578\" height=\"810\" \/><\/a><\/div><\/div><\/div><div class=\"wpex-slider-thumbnails sp-thumbnails\"><img loading=\"lazy\" decoding=\"async\" data-no-lazy=\"1\" class=\"wpex-slider-thumbnail sp-thumbnail skip-lazy\" src=\"https:\/\/i0.wp.com\/nuovazavalonolbia.com\/website\/wp-content\/uploads\/2021\/02\/CROCE-DEL-SUD.jpg?fit=578%2C810&#038;ssl=1\" alt=\"\" width=\"578\" height=\"810\" \/><\/div><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<span style=\"font-size: 28px;\">Croce del Sud<\/span>[\/vc_column_text][vc_separator css=&#8221;.vc_custom_1612368978489{padding-top:a 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]Elegante Marsina da sposo Blu Royal con gilet e plastron a contrasto in microfantasia grigio chiaro.[\/vc_column_text][vc_separator css=&#8221;.vc_custom_1612368978489{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]Nuova Zavalon Olbia \u00e8 rappresentante\u00a0 da oltre 20 anni della prestigiosa maison Scribano 1966 per tutta la Sardegna dei suoi prestigiosi abiti da sposo.<\/p>\n<p>Priv\u00e9 \u00e8 la collezione di\u00a0abiti da sposo dallo stile moderno e ricercato. Nella collezione\u00a0Priv\u00e9 Progressive\u00a0gli elementi innovativi son tanti, ma inseriti sempre in modo equilibrato, senza mai tralasciare eleganza e raffinatezza. Originalit\u00e0 sartoriale curata minuziosamente nei tessuti di alta qualit\u00e0 impreziositi con dettagli di Swaroski, fanno di ogni abito della collezione Priv\u00e9 un capolavoro da indossare nelle occasioni speciali. Se &#8220;Un diamante \u00e8 per sempre&#8221; un abito di questa collezione pu\u00f2 per sempre essere la migliore interpretazione di un evento.<\/p>\n<p>\u200d<\/p>\n<p>Vieni a provare il tuo abito nel nostri Atelier.<br \/>\nTi aspettiamo![\/vc_column_text][vc_separator css=&#8221;.vc_custom_1612368978489{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;]<div class=\"textcenter theme-button-expanded-wrap theme-button-wrap wpex-clr\"><a href=\"https:\/\/nuovazavalonolbia.com\/website\/appuntamento\/\" class=\"vcex-button theme-button minimal-border large align-center expanded expanded\" style=\"background:#c0c0c0;color:#ffffff;font-weight:300;text-transform:capitalize;\" data-wpex-hover='{&quot;background&quot;:&quot;#ffffff&quot;,&quot;color&quot;:&quot;#c0c0c0&quot;}'><span class=\"theme-button-inner\">PRENOTA LA TUA PROVA<\/span><\/a><\/div> [\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1612382354859{padding-top: 20px !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]Croce del Sud[\/vc_column_text][vc_separator css=&#8221;.vc_custom_1612368978489{padding-top:a 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]Elegante Marsina da sposo Blu Royal con gilet e plastron a contrasto in microfantasia grigio chiaro.[\/vc_column_text][vc_separator css=&#8221;.vc_custom_1612368978489{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_column_text]Nuova Zavalon Olbia \u00e8 rappresentante\u00a0 da oltre 20&hellip;<\/p>\n","protected":false},"author":1,"featured_media":465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"post_series":[],"class_list":["post-464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scribano-1966","entry","has-media"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nuovazavalonolbia.com\/website\/wp-content\/uploads\/2021\/02\/CROCE-DEL-SUD.jpg?fit=578%2C810&ssl=1","_links":{"self":[{"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/posts\/464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/comments?post=464"}],"version-history":[{"count":1,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/posts\/464\/revisions"}],"predecessor-version":[{"id":466,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/posts\/464\/revisions\/466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/media\/465"}],"wp:attachment":[{"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/media?parent=464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/categories?post=464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/tags?post=464"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/nuovazavalonolbia.com\/website\/wp-json\/wp\/v2\/post_series?post=464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}